{"id":2637,"date":"2025-04-06T08:38:08","date_gmt":"2025-04-06T12:38:08","guid":{"rendered":"https:\/\/explorepontiac.ottawavalleymedia.ca\/welcome-to-our-new-website\/"},"modified":"2025-04-06T08:40:41","modified_gmt":"2025-04-06T12:40:41","slug":"welcome-to-our-new-website","status":"publish","type":"post","link":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/","title":{"rendered":"Bienvenue sur notre nouveau site!"},"content":{"rendered":"\n<p>L\u2019Association touristique du Pontiac est fi\u00e8re de vous accueillir sur son site web fra\u00eechement renouvel\u00e9! Cette nouvelle plateforme a \u00e9t\u00e9 con\u00e7ue pour mieux pr\u00e9senter notre belle r\u00e9gion et rendre votre exp\u00e9rience de navigation plus agr\u00e9able.<\/p>\n\n\n\n<p>Au fil des semaines \u00e0 venir, nous ajouterons de nouveaux contenus, des photos, des id\u00e9es d\u2019activit\u00e9s, des informations pratiques, et bien plus encore pour vous aider \u00e0 planifier vos aventures dans le Pontiac.<\/p>\n\n\n\n<p>Merci de votre visite, et n\u2019h\u00e9sitez pas \u00e0 revenir souvent pour d\u00e9couvrir les nouveaut\u00e9s!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Association touristique du Pontiac est fi\u00e8re de vous accueillir sur son site web fra\u00eechement renouvel\u00e9! Cette nouvelle plateforme a \u00e9t\u00e9 con\u00e7ue pour mieux pr\u00e9senter notre belle r\u00e9gion et rendre votre exp\u00e9rience de navigation plus agr\u00e9able. Au fil des semaines \u00e0 venir, nous ajouterons de nouveaux contenus, des photos, des id\u00e9es d\u2019activit\u00e9s, des informations pratiques, et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-2637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bienvenue sur notre nouveau site! - Explore Pontiac<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bienvenue sur notre nouveau site! - Explore Pontiac\" \/>\n<meta property=\"og:description\" content=\"L\u2019Association touristique du Pontiac est fi\u00e8re de vous accueillir sur son site web fra\u00eechement renouvel\u00e9! Cette nouvelle plateforme a \u00e9t\u00e9 con\u00e7ue pour mieux pr\u00e9senter notre belle r\u00e9gion et rendre votre exp\u00e9rience de navigation plus agr\u00e9able. Au fil des semaines \u00e0 venir, nous ajouterons de nouveaux contenus, des photos, des id\u00e9es d\u2019activit\u00e9s, des informations pratiques, et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/\" \/>\n<meta property=\"og:site_name\" content=\"Explore Pontiac\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-06T12:38:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-06T12:40:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explorepontiac.ca\/wp-content\/uploads\/2025\/04\/WhitewaterCanoe2019-08711-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jon Stewart\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jon Stewart\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/\"},\"author\":{\"name\":\"Jon Stewart\",\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/#\\\/schema\\\/person\\\/38e387d7805b1e3231222a0baec99683\"},\"headline\":\"Bienvenue sur notre nouveau site!\",\"datePublished\":\"2025-04-06T12:38:08+00:00\",\"dateModified\":\"2025-04-06T12:40:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/\"},\"wordCount\":99,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explorepontiac.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/WhitewaterCanoe2019-08711-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/\",\"url\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/\",\"name\":\"Bienvenue sur notre nouveau site! - Explore Pontiac\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explorepontiac.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/WhitewaterCanoe2019-08711-scaled.jpg\",\"datePublished\":\"2025-04-06T12:38:08+00:00\",\"dateModified\":\"2025-04-06T12:40:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/#primaryimage\",\"url\":\"https:\\\/\\\/explorepontiac.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/WhitewaterCanoe2019-08711-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/explorepontiac.ca\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/WhitewaterCanoe2019-08711-scaled.jpg\",\"width\":2560,\"height\":1760,\"caption\":\"Whitewater\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/welcome-to-our-new-website\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bienvenue sur notre nouveau site!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/\",\"name\":\"Explore Pontiac\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/#organization\",\"name\":\"Explore Pontiac\",\"url\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/explorepontiac.ca\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/explore-pontiac-with-shadow.png\",\"contentUrl\":\"https:\\\/\\\/explorepontiac.ca\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/explore-pontiac-with-shadow.png\",\"width\":1389,\"height\":1330,\"caption\":\"Explore Pontiac\"},\"image\":{\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/explore.pontiac\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/#\\\/schema\\\/person\\\/38e387d7805b1e3231222a0baec99683\",\"name\":\"Jon Stewart\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f803e8c89c372b12b471c272efcbb04fd6aa78d65cd095d3045ab0377a9e0c7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f803e8c89c372b12b471c272efcbb04fd6aa78d65cd095d3045ab0377a9e0c7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f803e8c89c372b12b471c272efcbb04fd6aa78d65cd095d3045ab0377a9e0c7c?s=96&d=mm&r=g\",\"caption\":\"Jon Stewart\"},\"description\":\"Calumet Media &amp; Consulting\",\"sameAs\":[\"https:\\\/\\\/explorepontiac.ca\"],\"url\":\"https:\\\/\\\/explorepontiac.ca\\\/fr\\\/author\\\/joncalumetmedia-ca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bienvenue sur notre nouveau site! - Explore Pontiac","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/","og_locale":"fr_FR","og_type":"article","og_title":"Bienvenue sur notre nouveau site! - Explore Pontiac","og_description":"L\u2019Association touristique du Pontiac est fi\u00e8re de vous accueillir sur son site web fra\u00eechement renouvel\u00e9! Cette nouvelle plateforme a \u00e9t\u00e9 con\u00e7ue pour mieux pr\u00e9senter notre belle r\u00e9gion et rendre votre exp\u00e9rience de navigation plus agr\u00e9able. Au fil des semaines \u00e0 venir, nous ajouterons de nouveaux contenus, des photos, des id\u00e9es d\u2019activit\u00e9s, des informations pratiques, et [&hellip;]","og_url":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/","og_site_name":"Explore Pontiac","article_published_time":"2025-04-06T12:38:08+00:00","article_modified_time":"2025-04-06T12:40:41+00:00","og_image":[{"width":2560,"height":1760,"url":"https:\/\/explorepontiac.ca\/wp-content\/uploads\/2025\/04\/WhitewaterCanoe2019-08711-scaled.jpg","type":"image\/jpeg"}],"author":"Jon Stewart","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jon Stewart"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/#article","isPartOf":{"@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/"},"author":{"name":"Jon Stewart","@id":"https:\/\/explorepontiac.ca\/fr\/#\/schema\/person\/38e387d7805b1e3231222a0baec99683"},"headline":"Bienvenue sur notre nouveau site!","datePublished":"2025-04-06T12:38:08+00:00","dateModified":"2025-04-06T12:40:41+00:00","mainEntityOfPage":{"@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/"},"wordCount":99,"commentCount":0,"publisher":{"@id":"https:\/\/explorepontiac.ca\/fr\/#organization"},"image":{"@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/#primaryimage"},"thumbnailUrl":"https:\/\/explorepontiac.ca\/wp-content\/uploads\/2025\/04\/WhitewaterCanoe2019-08711-scaled.jpg","articleSection":["News"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/","url":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/","name":"Bienvenue sur notre nouveau site! - Explore Pontiac","isPartOf":{"@id":"https:\/\/explorepontiac.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/#primaryimage"},"image":{"@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/#primaryimage"},"thumbnailUrl":"https:\/\/explorepontiac.ca\/wp-content\/uploads\/2025\/04\/WhitewaterCanoe2019-08711-scaled.jpg","datePublished":"2025-04-06T12:38:08+00:00","dateModified":"2025-04-06T12:40:41+00:00","breadcrumb":{"@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/#primaryimage","url":"https:\/\/explorepontiac.ca\/wp-content\/uploads\/2025\/04\/WhitewaterCanoe2019-08711-scaled.jpg","contentUrl":"https:\/\/explorepontiac.ca\/wp-content\/uploads\/2025\/04\/WhitewaterCanoe2019-08711-scaled.jpg","width":2560,"height":1760,"caption":"Whitewater"},{"@type":"BreadcrumbList","@id":"https:\/\/explorepontiac.ca\/fr\/welcome-to-our-new-website\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/explorepontiac.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Bienvenue sur notre nouveau site!"}]},{"@type":"WebSite","@id":"https:\/\/explorepontiac.ca\/fr\/#website","url":"https:\/\/explorepontiac.ca\/fr\/","name":"Explore Pontiac","description":"","publisher":{"@id":"https:\/\/explorepontiac.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explorepontiac.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/explorepontiac.ca\/fr\/#organization","name":"Explore Pontiac","url":"https:\/\/explorepontiac.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/explorepontiac.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/explorepontiac.ca\/wp-content\/uploads\/2024\/03\/explore-pontiac-with-shadow.png","contentUrl":"https:\/\/explorepontiac.ca\/wp-content\/uploads\/2024\/03\/explore-pontiac-with-shadow.png","width":1389,"height":1330,"caption":"Explore Pontiac"},"image":{"@id":"https:\/\/explorepontiac.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/explore.pontiac\/"]},{"@type":"Person","@id":"https:\/\/explorepontiac.ca\/fr\/#\/schema\/person\/38e387d7805b1e3231222a0baec99683","name":"Jon Stewart","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f803e8c89c372b12b471c272efcbb04fd6aa78d65cd095d3045ab0377a9e0c7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f803e8c89c372b12b471c272efcbb04fd6aa78d65cd095d3045ab0377a9e0c7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f803e8c89c372b12b471c272efcbb04fd6aa78d65cd095d3045ab0377a9e0c7c?s=96&d=mm&r=g","caption":"Jon Stewart"},"description":"Calumet Media &amp; Consulting","sameAs":["https:\/\/explorepontiac.ca"],"url":"https:\/\/explorepontiac.ca\/fr\/author\/joncalumetmedia-ca\/"}]}},"_links":{"self":[{"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/posts\/2637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/comments?post=2637"}],"version-history":[{"count":1,"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/posts\/2637\/revisions"}],"predecessor-version":[{"id":2638,"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/posts\/2637\/revisions\/2638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/media\/2635"}],"wp:attachment":[{"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/media?parent=2637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/categories?post=2637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explorepontiac.ca\/fr\/wp-json\/wp\/v2\/tags?post=2637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}